{"id":1670,"date":"2014-11-21T17:38:00","date_gmt":"2014-11-21T22:38:00","guid":{"rendered":"https:\/\/www.precisionot.com\/?p=1670"},"modified":"2021-05-05T11:37:10","modified_gmt":"2021-05-05T15:37:10","slug":"faq-warum-verkaufen-sie-keine-70-km-cwdm-10g-optik-1350-1450-ranger","status":"publish","type":"post","link":"https:\/\/www.precisionot.com\/de\/faq-ldquowhy-donrsquot-you-sell-70km-cwdm-10g-optics-1350-1450-rangerdquo\/","title":{"rendered":"FAQ: \u201eWarum verkaufen Sie nicht 70 km CWDM 10G-Optiken im Bereich 1350\u20131450?\u201c"},"content":{"rendered":"<h2 class=\"wp-block-heading\" id=\"h-the-major-question\">Die gro\u00dfe Frage<\/h2>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-7387b849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<p class=\"wp-block-paragraph\">Beim Vergleich von Glasfaser- und Kupfernetzen ist Glasfaser oft der bevorzugte Datentr\u00e4ger. Glasfasernetze erm\u00f6glichen die Installation in Gebieten mit st\u00e4rkeren elektromagnetischen St\u00f6rungen, verf\u00fcgen \u00fcber l\u00e4ngere Verbindungsm\u00f6glichkeiten und k\u00f6nnen mehr Informationen \u00fcber gr\u00f6\u00dfere Entfernungen \u00fcbertragen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei den verschiedenen Anwendungen von Glasfasernetzen ist es wichtig sicherzustellen, dass die Daten erfolgreich von der Quelle zum Empf\u00e4nger gesendet werden. Wenn es zu Verlusten oder Reflexionen kommt, kann es zu einer Verschlechterung des Signals kommen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Oft werden wir gefragt, warum unser Unternehmen keine 10G-Langstreckenoptiken im Bereich 1350\u20131450 nm anbietet. Der Verlust durch Glas soll im Wellenl\u00e4ngenbereich von 1200\u20131600 nm im Allgemeinen gering sein, die Lichtdurchl\u00e4ssigkeit war jedoch in der Vergangenheit auf die Bereiche 1310 nm und 1550 nm beschr\u00e4nkt. Warum ist das?<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In diesem Blogbeitrag besprechen wir die optische R\u00fcckflussd\u00e4mpfung und die Logik hinter der Beschr\u00e4nkung der Licht\u00fcbertragung auf die Bereiche 1310 nm und 1550 nm.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-00-14-pm.png\" alt=\" Vergleich von Glasfaser- und Kupfernetzwerken\" class=\"wp-image-3212\" width=\"247\" height=\"152\" srcset=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-00-14-pm.png 518w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-00-14-pm-300x185.png 300w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-00-14-pm-16x10.png 16w\" sizes=\"(max-width: 247px) 100vw, 247px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-02-19-pm.png\" alt=\"Wellenleiter\" class=\"wp-image-3213\" width=\"221\" height=\"127\" srcset=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-02-19-pm.png 523w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-02-19-pm-300x172.png 300w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-02-19-pm-16x9.png 16w\" sizes=\"(max-width: 221px) 100vw, 221px\" \/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large is-resized\"><img decoding=\"async\" src=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-03-17-pm.png\" alt=\"Mikrobiegeverlust\" class=\"wp-image-3214\" width=\"240\" height=\"133\" srcset=\"https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-03-17-pm.png 489w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-03-17-pm-300x166.png 300w, https:\/\/www.precisionot.com\/wp-content\/uploads\/screen-shot-2014-10-30-at-1-03-17-pm-16x9.png 16w\" sizes=\"(max-width: 240px) 100vw, 240px\" \/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-optical-return-loss\">&nbsp;<strong>Optische R\u00fcckflussd\u00e4mpfung<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die optische R\u00fcckflussd\u00e4mpfung (auch ORL genannt) ist das Ma\u00df f\u00fcr die Lichtd\u00e4mpfung vom Eingangsende der Faser bis zum Ausgangsende. Im Wesentlichen handelt es sich dabei um die Lichtmenge, die durch ein Glasfaserkabel reflektiert wird. ORL wird im Allgemeinen in Dezibel (dB) ausgedr\u00fcckt; Je h\u00f6her die Dezibelzahl, desto geringer ist die Lichtreflexion. Generell gilt: Je geringer die R\u00fcckflussd\u00e4mpfung, desto gr\u00f6\u00dfer die Entfernung, die das Licht zur\u00fccklegen kann, bevor es verst\u00e4rkt werden muss. ORL kann als Gesamt-ORL oder Abschnitts-ORL gemessen werden.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Der D\u00e4mpfungsgrad des Kabels h\u00e4ngt von seiner Wellenl\u00e4nge ab. Tabelle 1 zeigt die D\u00e4mpfung\/Absorption sowohl f\u00fcr Singlemode- als auch f\u00fcr Multimode-Fasern. Der Absorptionspeak bei 1000 nm wird durch die allgemeinen Eigenschaften von Singlemode-Fasern verursacht, und der Peak bei 1400 nm entsteht durch in der Faser verbleibende Wasserspuren. Dies ist ein wesentlicher Faktor, der zur Begrenzung der Licht\u00fcbertragung beitr\u00e4gt.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Reihe spezifischerer Elemente der optischen R\u00fcckflussd\u00e4mpfung wurden zusammengef\u00fchrt, um die Wellenl\u00e4ngenbeschr\u00e4nkung auf die Bereiche 1310 nm und 1550 nm weiter zu erkl\u00e4ren: Faserbiegeverlust \u00fcber 1600 nm, Rayleigh-Streuung und Hydroxylionen (OH)-Absorption mit Schwerpunkt um 1385 nm.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-bend-loss\"><strong>Biegeverlust<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Biegeverluste sind ein h\u00e4ufiges Problem, das auftritt, wenn Kabel so weit gebogen werden, dass das Lichtsignal nicht mehr ordnungsgem\u00e4\u00df durch das Kabel wandern kann. Im Allgemeinen sind die Biegeverluste bei l\u00e4ngeren Wellenl\u00e4ngen gr\u00f6\u00dfer; Dadurch wird der nutzbare Wellenl\u00e4ngenbereich der Singlemode-Faser eingeschr\u00e4nkt. Bei Multimode-Fasern ist der Biegeradius bei Transversalmoden h\u00f6herer Ordnung normalerweise kleiner.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-types-of-bend-losses\"><strong>Arten von Biegeverlusten<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Es gibt zwei allgemeine Arten von Biegeverlusten: Mikrobiegung und Makrobiegung. Mikrokr\u00fcmmungsverluste entstehen durch geringf\u00fcgige M\u00e4ngel in der Glasfaser (z. B. unsachgem\u00e4\u00dfe Beschichtungsanwendungen, unsachgem\u00e4\u00dfe Verkabelungsverfahren). Diese Art von Verlust erh\u00f6ht im Allgemeinen die D\u00e4mpfung, da Moden niedriger Ordnung mit Moden h\u00f6herer Ordnung gekoppelt werden. Makrobiegungsverluste treten auf, wenn der Biegeradius einer Faser im Vergleich zum Faserdurchmesser gr\u00f6\u00dfer ist, insbesondere wenn der Kr\u00fcmmungsradius weniger als einige Zentimeter betr\u00e4gt.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-rayleigh-scattering\"><strong>Rayleigh-Streuung<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Rayleigh-Streuung ist die elastische Streuung von Lichtstrahlung durch Teilchen, die viel kleiner als die Wellenl\u00e4nge des Lichts sind. Interferenzen mit Partikeln, die kleiner als die Lichtwellenl\u00e4nge sind, l\u00f6sen die Reaktion aus, wodurch sich das Licht auf seinem Weg durch die Faser in alle Richtungen verteilt. Je n\u00e4her die Wellenl\u00e4nge im Vergleich zur Partikelgr\u00f6\u00dfe liegt, desto gr\u00f6\u00dfer ist die auftretende Streuung.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;Da ein Gro\u00dfteil des Streulichts einer Faser seitlich aus der Faser austritt, wird nur ein kleiner Teil des Streulichts zur\u00fcckgestreut und kann in den Faserkern geleitet werden. Aus diesem Grund sind die R\u00fcckflussverluste in der Regel sehr hoch.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-absorption-hydroxyl-ion\"><strong>Absorption: Hydroxylion<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Die durch die Umwandlung optischer Leistung in eine andere Energieform verursachte D\u00e4mpfung wird als Absorption bezeichnet. Es gibt zwei Unterkategorien der Absorption: extrinsisch und intrinsisch. Die intrinsische Absorption wird durch Vibrationsresonanzen im UV- und IR-Bereich des elektromagnetischen Spektrums verursacht, wohingegen die extrinsische Absorption durch Rayleigh-Streuung durch Verunreinigungen im Glasfaserkabel verursacht wird.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Eine Hauptart der Absorption ist die Absorption von Hydroxylionen (OH). Dies ist eine der m\u00f6glichen Theorien zur Erkl\u00e4rung der Beschr\u00e4nkung der Licht\u00fcbertragung auf 1310 nm und 1550 nm. Wie bereits kurz erw\u00e4hnt, dienen eingefangene Hydroxylionen, die im Wasser verbleiben, als Verunreinigung, die D\u00e4mpfung und Signalverlust verursacht. Dies kann erkl\u00e4ren, warum die meisten \u00dcbertragungssysteme bei einer Wellenl\u00e4nge von 1,31 Mikrometern arbeiten.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"h-how-to-test-for-orl\"><strong>So testen Sie auf ORL<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><em>Es gibt zwei Haupttechniken zum Testen der optischen R\u00fcckflussd\u00e4mpfung:<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">1)&nbsp;<strong>OCWR:&nbsp;<\/strong>Ein als optisches CW-Reflektometer (OCWR) bekanntes Instrument misst eine grundlegende Leistungsmessermessung der Startleistung; Von dort aus vergleicht es die Messung mit der zur\u00fcckreflektierten optischen Leistung. Ein Nachteil dieser Methode besteht darin, dass sie nicht zwischen Rayleigh-R\u00fcckstreuung und Fresnel-Reflexion unterscheiden kann. Aus diesem Grund umfassen alle Messungen eine Rayleigh-R\u00fcckstreuung von mindestens 1,5.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&nbsp;2)&nbsp;<strong>OTDR:&nbsp;<\/strong>Der gebr\u00e4uchlichere Ansatz, bekannt als Zeitbereichsmethode, verwendet das optische Zeitbereichsreflektometer (OTDR), um die optische R\u00fcckflussd\u00e4mpfung zu testen. Reflexionsmessungen werden durch Injektion optischer Impulse in die zu pr\u00fcfende Faser durchgef\u00fchrt. Gleichzeitig ist es in der Lage, das in der gesamten Faser gestreute oder reflektierte Licht zu extrahieren. Ein Vorteil der Verwendung des OTDR besteht darin, dass es zwischen Rayleigh- und Fresnel-Aktivit\u00e4t unterscheiden kann.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Bei weiteren Fragen wenden Sie sich bitte an&nbsp;<a href=\"mailto:ma*******@*********ot.com\" data-original-string=\"bj3mR35xBO3obrWfx1IrwA==e23QshfQ44M7WO9\/5NxKwumul46WZyK8k8y5\/UlP\/zcavE=\" title=\"Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.\"><span \n                data-original-string='Xfm3LE5VzlBg3kZJpYJFkw==e234UYx8w9lPdN5BVC6zfkBXAmcQA5fg3CSr+a96cSDc1Y='\n                class='apbct-email-encoder'\n                title='Dieser Kontakt wurde von Anti-Spam by CleanTalk verschl\u00fcsselt. Klicken Sie hier, um ihn zu entschl\u00fcsseln. Um die Entschl\u00fcsselung abzuschlie\u00dfen, stellen Sie sicher, dass JavaScript in Ihrem Browser aktiviert ist.'>ma<span class=\"apbct-blur\">*******<\/span>@<span class=\"apbct-blur\">*********<\/span>ot.com<\/span><\/a>&nbsp;oder besuchen Sie unsere Website: <a href=\"https:\/\/www.precisionot.com\/de\/\">www.precisionot.com<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Die gro\u00dfe Frage<\/p>","protected":false},"author":2,"featured_media":1671,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","site-sidebar-layout":"default","site-content-layout":"default","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[6],"tags":[],"class_list":["post-1670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/posts\/1670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/comments?post=1670"}],"version-history":[{"count":0,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/posts\/1670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/media\/1671"}],"wp:attachment":[{"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/media?parent=1670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/categories?post=1670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.precisionot.com\/de\/wp-json\/wp\/v2\/tags?post=1670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}